{"id":1428,"date":"2019-03-26T09:56:45","date_gmt":"2019-03-26T08:56:45","guid":{"rendered":"http:\/\/archimedys.fr\/?p=1428"},"modified":"2025-09-15T13:48:11","modified_gmt":"2025-09-15T13:48:11","slug":"archimedys-beton","status":"publish","type":"post","link":"https:\/\/archimedys.fr\/de\/archimedys-beton\/","title":{"rendered":"Archimedys\u2122 von Betonherstellern verwendet"},"content":{"rendered":"<h3 class=\"wp-block-heading\">Archimedys\u2122 von Betonherstellern verwendet <\/h3>\n\n\n\n<p>Hersteller von Beton und M\u00f6rtel verwenden h\u00e4ufig F\u00f6rderschnecken aus Stahl, die mit Polyurethan beschichtet sind. Diese Beschichtung dient unter anderem dazu, Abrieb und Korrosion zu verhindern. Infolge der Verwendung dieser Schnecken treten zahlreiche Wartungsprobleme auf. Um den Betonherstellern zu helfen, haben wir die&nbsp;<strong>Archimedische Schraube <\/strong>Archimedys\u2122. Hierbei handelt es sich um eine Schnecke aus Polymer, die sich dadurch auszeichnet, dass sie eine einfache Reinigung von Beton erm\u00f6glicht und sehr abriebfest ist. Diese Schnecke, die Sie selbst zusammenbauen k\u00f6nnen, erm\u00f6glicht Ihnen eine schnelle Wartung Ihrer Ger\u00e4te bei Zwischenf\u00e4llen.<\/p>\n\n\n\n<p>Im dargestellten Fall entleert unser Kunde die Kreisel in einen F\u00f6rderer mit Sp\u00fclrampe und sorgt f\u00fcr das Waschen und Trennen des Kieses. <\/p>\n\n\n\n<p>Je nach Art Ihrer Aktivit\u00e4t kann die Archimedys\u2122-Schraube optimiert werden: Unser Konzept ist vollst\u00e4ndig modular aufgebaut. Wir helfen Ihnen dabei&nbsp;<a href=\"https:\/\/archimedys.fr\/de\/calculateur\/\">die Gr\u00f6\u00dfe der Schraube einfach berechnen<\/a>&nbsp;der Ihren Bed\u00fcrfnissen entspricht. <\/p>\n\n\n\n<p> Die Archimedys\u2122-Schnecke kann in einen bestehenden oder neuen Schneckenf\u00f6rderer eingebaut werden. Ihre St\u00e4rke ist die vereinfachte Wartung, die eine echte Zeitersparnis mit sich bringt. Au\u00dferdem muss bei Verschlei\u00df nicht mehr die gesamte Schnecke ausgetauscht werden, sondern nur noch die defekten Teile.  <\/p>\n\n\n\n<p>Wenn Sie mehr \u00fcber unsere\u00a0<strong>Archimedische Schraube <\/strong>Archimedys\u2122 aus Polymer, laden wir Sie dazu ein\u00a0<a href=\"https:\/\/archimedys.fr\/de\/contact\/\" data-type=\"link\" data-id=\"https:\/\/archimedys.fr\/contact\/\">uns kontaktieren<\/a>\u00a0ohne l\u00e4nger warten zu m\u00fcssen. Wir begleiten Sie bei all Ihren Projekten und schlagen Ihnen die Ausr\u00fcstung vor, die am besten zu Ihrer T\u00e4tigkeit passt.<br><\/p>","protected":false},"excerpt":{"rendered":"<p>Archimedys\u2122 utilis\u00e9e par les fabricants de b\u00e9ton Les fabricants de b\u00e9ton et mortiers utilisent souvent des vis de transport en acier rev\u00eatues de polyur\u00e9thane. Ce rev\u00eatement permet entre autres d\u2019\u00e9viter l\u2019abrasion et la corrosion. De nombreux probl\u00e8mes de maintenance apparaissent suite \u00e0 l&rsquo;utilisation de ces vis. Pour venir en aide aux fabricants de b\u00e9ton nous [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7262,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1428","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-realisations"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archimedys\u2122 utilis\u00e9e par les fabricants de b\u00e9ton - Archimedys<\/title>\n<meta name=\"description\" content=\"Vis d&#039;Archim\u00e8de Archimedys\u2122 en polym\u00e8re qui emp\u00eache l&#039;adh\u00e9rence du b\u00e9ton. Elle est tr\u00e8s facile \u00e0 nettoyer et con\u00e7ue de fa\u00e7on \u00e0 \u00eatre hautement r\u00e9sistante.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/archimedys.fr\/de\/archimedys-beton\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archimedys\u2122 utilis\u00e9e par les fabricants de b\u00e9ton - Archimedys\" \/>\n<meta property=\"og:description\" content=\"Vis d&#039;Archim\u00e8de Archimedys\u2122 en polym\u00e8re qui emp\u00eache l&#039;adh\u00e9rence du b\u00e9ton. Elle est tr\u00e8s facile \u00e0 nettoyer et con\u00e7ue de fa\u00e7on \u00e0 \u00eatre hautement r\u00e9sistante.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archimedys.fr\/de\/archimedys-beton\/\" \/>\n<meta property=\"og:site_name\" content=\"Archimedys\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-26T08:56:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-15T13:48:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/archimedys.fr\/wp-content\/uploads\/2019\/03\/vis-beton-768x768-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"archimedysfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"archimedysfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/archimedys.fr\\\/archimedys-beton\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archimedys.fr\\\/archimedys-beton\\\/\"},\"author\":{\"name\":\"archimedysfr\",\"@id\":\"https:\\\/\\\/archimedys.fr\\\/#\\\/schema\\\/person\\\/0f326e2d3d04e71bf982c6dbcc6c070f\"},\"headline\":\"Archimedys\u2122 utilis\u00e9e par les fabricants de b\u00e9ton\",\"datePublished\":\"2019-03-26T08:56:45+00:00\",\"dateModified\":\"2025-09-15T13:48:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/archimedys.fr\\\/archimedys-beton\\\/\"},\"wordCount\":294,\"publisher\":{\"@id\":\"https:\\\/\\\/archimedys.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/archimedys.fr\\\/archimedys-beton\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archimedys.fr\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/vis-beton-768x768-1.jpg\",\"articleSection\":[\"R\u00e9alisations\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archimedys.fr\\\/archimedys-beton\\\/\",\"url\":\"https:\\\/\\\/archimedys.fr\\\/archimedys-beton\\\/\",\"name\":\"Archimedys\u2122 utilis\u00e9e par les fabricants de b\u00e9ton - Archimedys\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archimedys.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archimedys.fr\\\/archimedys-beton\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archimedys.fr\\\/archimedys-beton\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archimedys.fr\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/vis-beton-768x768-1.jpg\",\"datePublished\":\"2019-03-26T08:56:45+00:00\",\"dateModified\":\"2025-09-15T13:48:11+00:00\",\"description\":\"Vis d'Archim\u00e8de Archimedys\u2122 en polym\u00e8re qui emp\u00eache l'adh\u00e9rence du b\u00e9ton. Elle est tr\u00e8s facile \u00e0 nettoyer et con\u00e7ue de fa\u00e7on \u00e0 \u00eatre hautement r\u00e9sistante.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archimedys.fr\\\/archimedys-beton\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archimedys.fr\\\/archimedys-beton\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/archimedys.fr\\\/archimedys-beton\\\/#primaryimage\",\"url\":\"https:\\\/\\\/archimedys.fr\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/vis-beton-768x768-1.jpg\",\"contentUrl\":\"https:\\\/\\\/archimedys.fr\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/vis-beton-768x768-1.jpg\",\"width\":768,\"height\":768,\"caption\":\"R\u00e9novation convoyeur \u00e0 vis acier\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archimedys.fr\\\/archimedys-beton\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/archimedys.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archimedys\u2122 utilis\u00e9e par les fabricants de b\u00e9ton\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archimedys.fr\\\/#website\",\"url\":\"https:\\\/\\\/archimedys.fr\\\/\",\"name\":\"Archimedys\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/archimedys.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archimedys.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/archimedys.fr\\\/#organization\",\"name\":\"Archimedys\",\"url\":\"https:\\\/\\\/archimedys.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/archimedys.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/archimedys.fr\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Design-sans-titre.svg\",\"contentUrl\":\"https:\\\/\\\/archimedys.fr\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Design-sans-titre.svg\",\"width\":350,\"height\":100,\"caption\":\"Archimedys\"},\"image\":{\"@id\":\"https:\\\/\\\/archimedys.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/archimedys.fr\\\/#\\\/schema\\\/person\\\/0f326e2d3d04e71bf982c6dbcc6c070f\",\"name\":\"archimedysfr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fd139960b5e96d7b31909239e427395b1670a5fce144ef6fab09f0962547e133?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fd139960b5e96d7b31909239e427395b1670a5fce144ef6fab09f0962547e133?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fd139960b5e96d7b31909239e427395b1670a5fce144ef6fab09f0962547e133?s=96&d=mm&r=g\",\"caption\":\"archimedysfr\"},\"url\":\"https:\\\/\\\/archimedys.fr\\\/de\\\/author\\\/archimedysfr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archimedys\u2122 utilis\u00e9e par les fabricants de b\u00e9ton - Archimedys","description":"Vis d'Archim\u00e8de Archimedys\u2122 en polym\u00e8re qui emp\u00eache l'adh\u00e9rence du b\u00e9ton. Elle est tr\u00e8s facile \u00e0 nettoyer et con\u00e7ue de fa\u00e7on \u00e0 \u00eatre hautement r\u00e9sistante.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/archimedys.fr\/de\/archimedys-beton\/","og_locale":"de_DE","og_type":"article","og_title":"Archimedys\u2122 utilis\u00e9e par les fabricants de b\u00e9ton - Archimedys","og_description":"Vis d'Archim\u00e8de Archimedys\u2122 en polym\u00e8re qui emp\u00eache l'adh\u00e9rence du b\u00e9ton. Elle est tr\u00e8s facile \u00e0 nettoyer et con\u00e7ue de fa\u00e7on \u00e0 \u00eatre hautement r\u00e9sistante.","og_url":"https:\/\/archimedys.fr\/de\/archimedys-beton\/","og_site_name":"Archimedys","article_published_time":"2019-03-26T08:56:45+00:00","article_modified_time":"2025-09-15T13:48:11+00:00","og_image":[{"width":768,"height":768,"url":"https:\/\/archimedys.fr\/wp-content\/uploads\/2019\/03\/vis-beton-768x768-1.jpg","type":"image\/jpeg"}],"author":"archimedysfr","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"archimedysfr","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/archimedys.fr\/archimedys-beton\/#article","isPartOf":{"@id":"https:\/\/archimedys.fr\/archimedys-beton\/"},"author":{"name":"archimedysfr","@id":"https:\/\/archimedys.fr\/#\/schema\/person\/0f326e2d3d04e71bf982c6dbcc6c070f"},"headline":"Archimedys\u2122 utilis\u00e9e par les fabricants de b\u00e9ton","datePublished":"2019-03-26T08:56:45+00:00","dateModified":"2025-09-15T13:48:11+00:00","mainEntityOfPage":{"@id":"https:\/\/archimedys.fr\/archimedys-beton\/"},"wordCount":294,"publisher":{"@id":"https:\/\/archimedys.fr\/#organization"},"image":{"@id":"https:\/\/archimedys.fr\/archimedys-beton\/#primaryimage"},"thumbnailUrl":"https:\/\/archimedys.fr\/wp-content\/uploads\/2019\/03\/vis-beton-768x768-1.jpg","articleSection":["R\u00e9alisations"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/archimedys.fr\/archimedys-beton\/","url":"https:\/\/archimedys.fr\/archimedys-beton\/","name":"Archimedys\u2122 utilis\u00e9e par les fabricants de b\u00e9ton - Archimedys","isPartOf":{"@id":"https:\/\/archimedys.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archimedys.fr\/archimedys-beton\/#primaryimage"},"image":{"@id":"https:\/\/archimedys.fr\/archimedys-beton\/#primaryimage"},"thumbnailUrl":"https:\/\/archimedys.fr\/wp-content\/uploads\/2019\/03\/vis-beton-768x768-1.jpg","datePublished":"2019-03-26T08:56:45+00:00","dateModified":"2025-09-15T13:48:11+00:00","description":"Vis d'Archim\u00e8de Archimedys\u2122 en polym\u00e8re qui emp\u00eache l'adh\u00e9rence du b\u00e9ton. Elle est tr\u00e8s facile \u00e0 nettoyer et con\u00e7ue de fa\u00e7on \u00e0 \u00eatre hautement r\u00e9sistante.","breadcrumb":{"@id":"https:\/\/archimedys.fr\/archimedys-beton\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archimedys.fr\/archimedys-beton\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/archimedys.fr\/archimedys-beton\/#primaryimage","url":"https:\/\/archimedys.fr\/wp-content\/uploads\/2019\/03\/vis-beton-768x768-1.jpg","contentUrl":"https:\/\/archimedys.fr\/wp-content\/uploads\/2019\/03\/vis-beton-768x768-1.jpg","width":768,"height":768,"caption":"R\u00e9novation convoyeur \u00e0 vis acier"},{"@type":"BreadcrumbList","@id":"https:\/\/archimedys.fr\/archimedys-beton\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/archimedys.fr\/"},{"@type":"ListItem","position":2,"name":"Archimedys\u2122 utilis\u00e9e par les fabricants de b\u00e9ton"}]},{"@type":"WebSite","@id":"https:\/\/archimedys.fr\/#website","url":"https:\/\/archimedys.fr\/","name":"Archimedys","description":"","publisher":{"@id":"https:\/\/archimedys.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archimedys.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/archimedys.fr\/#organization","name":"Archimedys","url":"https:\/\/archimedys.fr\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/archimedys.fr\/#\/schema\/logo\/image\/","url":"https:\/\/archimedys.fr\/wp-content\/uploads\/2025\/03\/Design-sans-titre.svg","contentUrl":"https:\/\/archimedys.fr\/wp-content\/uploads\/2025\/03\/Design-sans-titre.svg","width":350,"height":100,"caption":"Archimedys"},"image":{"@id":"https:\/\/archimedys.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/archimedys.fr\/#\/schema\/person\/0f326e2d3d04e71bf982c6dbcc6c070f","name":"archimedysfr","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fd139960b5e96d7b31909239e427395b1670a5fce144ef6fab09f0962547e133?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fd139960b5e96d7b31909239e427395b1670a5fce144ef6fab09f0962547e133?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fd139960b5e96d7b31909239e427395b1670a5fce144ef6fab09f0962547e133?s=96&d=mm&r=g","caption":"archimedysfr"},"url":"https:\/\/archimedys.fr\/de\/author\/archimedysfr\/"}]}},"_links":{"self":[{"href":"https:\/\/archimedys.fr\/de\/wp-json\/wp\/v2\/posts\/1428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archimedys.fr\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archimedys.fr\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archimedys.fr\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/archimedys.fr\/de\/wp-json\/wp\/v2\/comments?post=1428"}],"version-history":[{"count":3,"href":"https:\/\/archimedys.fr\/de\/wp-json\/wp\/v2\/posts\/1428\/revisions"}],"predecessor-version":[{"id":8125,"href":"https:\/\/archimedys.fr\/de\/wp-json\/wp\/v2\/posts\/1428\/revisions\/8125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archimedys.fr\/de\/wp-json\/wp\/v2\/media\/7262"}],"wp:attachment":[{"href":"https:\/\/archimedys.fr\/de\/wp-json\/wp\/v2\/media?parent=1428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archimedys.fr\/de\/wp-json\/wp\/v2\/categories?post=1428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archimedys.fr\/de\/wp-json\/wp\/v2\/tags?post=1428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}